{"id":268,"date":"2020-06-22T11:37:00","date_gmt":"2020-06-22T09:37:00","guid":{"rendered":"https:\/\/teambananenflanke.de\/trier\/?p=268"},"modified":"2025-04-02T11:38:19","modified_gmt":"2025-04-02T09:38:19","slug":"absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup","status":"publish","type":"post","link":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/","title":{"rendered":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Da bis jetzt bis Ende August keine Veranstaltungen stattfinden d\u00fcrfen, haben wir uns jetzt schon schweren Herzens entschieden, das wir unser Turnier im September absagen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sollte ein Alternativ Termin anstehen werden wir es rechtzeitig \u00fcber unsere WEB Seite und Facebookseite bekanntgeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich hoffe Ihr habt Verst\u00e4ndniss daf\u00fcr aber uns ist es Ende August bis zum 12.September zu Kurzfristig etwas zu planen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Euer Vorstand und Orga Team.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da bis jetzt bis Ende August keine Veranstaltungen stattfinden d\u00fcrfen, haben wir uns jetzt schon schweren Herzens entschieden, das wir unser Turnier im September absagen. Sollte ein Alternativ Termin anstehen werden wir es rechtzeitig \u00fcber unsere WEB Seite und Facebookseite bekanntgeben. Ich hoffe Ihr habt Verst\u00e4ndniss daf\u00fcr aber uns ist es Ende August bis zum [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-268","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.\" \/>\n<meta property=\"og:description\" content=\"Da bis jetzt bis Ende August keine Veranstaltungen stattfinden d\u00fcrfen, haben wir uns jetzt schon schweren Herzens entschieden, das wir unser Turnier im September absagen. Sollte ein Alternativ Termin anstehen werden wir es rechtzeitig \u00fcber unsere WEB Seite und Facebookseite bekanntgeben. Ich hoffe Ihr habt Verst\u00e4ndniss daf\u00fcr aber uns ist es Ende August bis zum [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/\" \/>\n<meta property=\"og:site_name\" content=\"Team Bananenflanke\u00ae Trier e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T09:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T09:38:19+00:00\" \/>\n<meta name=\"author\" content=\"Marina Spielmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Spielmann\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/\"},\"author\":{\"name\":\"Marina Spielmann\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/#\\\/schema\\\/person\\\/67411e413827b1aa925e7bab0bb6f49c\"},\"headline\":\"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup\",\"datePublished\":\"2020-06-22T09:37:00+00:00\",\"dateModified\":\"2025-04-02T09:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/\"},\"wordCount\":78,\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/\",\"url\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/\",\"name\":\"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/#website\"},\"datePublished\":\"2020-06-22T09:37:00+00:00\",\"dateModified\":\"2025-04-02T09:38:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/#\\\/schema\\\/person\\\/67411e413827b1aa925e7bab0bb6f49c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/2020\\\/06\\\/22\\\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/#website\",\"url\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/\",\"name\":\"Team Bananenflanke\u00ae Trier e.V.\",\"description\":\"Fu\u00dfball kennt keine Grenzen!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/#\\\/schema\\\/person\\\/67411e413827b1aa925e7bab0bb6f49c\",\"name\":\"Marina Spielmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g\",\"caption\":\"Marina Spielmann\"},\"sameAs\":[\"https:\\\/\\\/teambananenflanke.de\\\/trier\"],\"url\":\"https:\\\/\\\/team-bananenflanke.de\\\/trier\\\/author\\\/marina-spielmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/","og_locale":"de_DE","og_type":"article","og_title":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.","og_description":"Da bis jetzt bis Ende August keine Veranstaltungen stattfinden d\u00fcrfen, haben wir uns jetzt schon schweren Herzens entschieden, das wir unser Turnier im September absagen. Sollte ein Alternativ Termin anstehen werden wir es rechtzeitig \u00fcber unsere WEB Seite und Facebookseite bekanntgeben. Ich hoffe Ihr habt Verst\u00e4ndniss daf\u00fcr aber uns ist es Ende August bis zum [&hellip;]","og_url":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/","og_site_name":"Team Bananenflanke\u00ae Trier e.V.","article_published_time":"2020-06-22T09:37:00+00:00","article_modified_time":"2025-04-02T09:38:19+00:00","author":"Marina Spielmann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marina Spielmann"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/#article","isPartOf":{"@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/"},"author":{"name":"Marina Spielmann","@id":"https:\/\/team-bananenflanke.de\/trier\/#\/schema\/person\/67411e413827b1aa925e7bab0bb6f49c"},"headline":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup","datePublished":"2020-06-22T09:37:00+00:00","dateModified":"2025-04-02T09:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/"},"wordCount":78,"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/","url":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/","name":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup - Team Bananenflanke\u00ae Trier e.V.","isPartOf":{"@id":"https:\/\/team-bananenflanke.de\/trier\/#website"},"datePublished":"2020-06-22T09:37:00+00:00","dateModified":"2025-04-02T09:38:19+00:00","author":{"@id":"https:\/\/team-bananenflanke.de\/trier\/#\/schema\/person\/67411e413827b1aa925e7bab0bb6f49c"},"breadcrumb":{"@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/team-bananenflanke.de\/trier\/2020\/06\/22\/absage-fuer-unseren-termin-fuer-4-bananenflanke-mosel-cup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/team-bananenflanke.de\/trier\/"},{"@type":"ListItem","position":2,"name":"Absage f\u00fcr unseren Termin f\u00fcr 4.Bananenflanke Mosel-Cup"}]},{"@type":"WebSite","@id":"https:\/\/team-bananenflanke.de\/trier\/#website","url":"https:\/\/team-bananenflanke.de\/trier\/","name":"Team Bananenflanke\u00ae Trier e.V.","description":"Fu\u00dfball kennt keine Grenzen!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/team-bananenflanke.de\/trier\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/team-bananenflanke.de\/trier\/#\/schema\/person\/67411e413827b1aa925e7bab0bb6f49c","name":"Marina Spielmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67b7b235c5f3ac9fe6b4b1e82a4d2cfffc29c335db879d461a2cb5fffe85de6a?s=96&d=mm&r=g","caption":"Marina Spielmann"},"sameAs":["https:\/\/teambananenflanke.de\/trier"],"url":"https:\/\/team-bananenflanke.de\/trier\/author\/marina-spielmann\/"}]}},"_links":{"self":[{"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/posts\/268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":1,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/posts\/268\/revisions"}],"predecessor-version":[{"id":269,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/posts\/268\/revisions\/269"}],"wp:attachment":[{"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/media?parent=268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/categories?post=268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/team-bananenflanke.de\/trier\/wp-json\/wp\/v2\/tags?post=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}